{"id":13253,"date":"2023-02-15T11:17:32","date_gmt":"2023-02-15T10:17:32","guid":{"rendered":"https:\/\/docs.kentix.com\/knowledge-base\/multisensor-door-ble-sans-fil-manuel-dutilisation\/"},"modified":"2026-07-02T09:11:40","modified_gmt":"2026-07-02T07:11:40","slug":"multisensor-door-ble-sans-fil-manuel-dutilisation","status":"publish","type":"ht_kb","link":"https:\/\/docs.kentix.com\/fr\/knowledge-base\/multisensor-door-ble-sans-fil-manuel-dutilisation\/","title":{"rendered":"MultiSensor-DOOR (BLE sans fil) - MANUEL D&rsquo;UTILISATION"},"content":{"rendered":"\n<pre class=\"wp-block-preformatted\"><a href=\"https:\/\/docs.kentix.com\/fr\/knowledge-base\/multisensor-door-fiche-technique-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">FICHE TECHNIQUE PORTE MULTISENSOR-DOOR<\/a><\/pre>\n\n<p class=\"wp-block-paragraph\">Le MultiSensor-DOOR-BLE est un MultiSensor fonctionnant sur piles et pouvant \u00eatre mis en r\u00e9seau par radio. Le capteur est particuli\u00e8rement adapt\u00e9 \u00e0 la surveillance des fen\u00eatres et des portes, mais peut \u00e9galement \u00eatre utilis\u00e9 pour la surveillance de l&rsquo;environnement dans les racks informatiques. <\/p>\n\n<p class=\"wp-block-paragraph\">Pour fonctionner par radio, le MultiSensor-DOOR-BLE a besoin d&rsquo;une station distante appropri\u00e9e. Cette contrepartie radio est constitu\u00e9e par les MultiSensor compatibles r\u00e9seau (MultiSensor-LAN-BLE ou MultiSensor-TI-BLE), qui font \u00e9galement office de passerelle Ethernet radio. <\/p>\n\n<p class=\"wp-block-paragraph\">Pour la gestion centrale, un SiteManager ou un AlarmManager en mode MAIN-DEVICE est n\u00e9cessaire. L&rsquo;apprentissage et la configuration se font enti\u00e8rement via l&rsquo;interface web KentixONE. La port\u00e9e radio entre la passerelle (MultiSensor-LAN-BLE ou MultiSensor-TI-BLE) et MultiSensor-DOOR-BLE peut aller jusqu&rsquo;\u00e0 20m. Jusqu&rsquo;\u00e0 25 capteurs radio peuvent \u00eatre programm\u00e9s sur une passerelle Ethernet sans fil.   <\/p>\n\n<h2 class=\"wp-block-heading\">Consignes de s\u00e9curit\u00e9<\/h2>\n\n<div class=\"wp-block-ht-blocks-accordion wp-block-hb-accordion\"><div class=\"wp-block-hb-accordion__section\" data-ht-blocks-accordion-block-state=\"closed\"><div class=\"wp-block-hb-accordion__title\"><span>Installation<\/span><\/div><div class=\"wp-block-hb-accordion__content\"><div class=\"wp-block-hb-accordion__contentwrap\">L&rsquo;installation et la mise en service ne doivent \u00eatre effectu\u00e9es que par un personnel sp\u00e9cialis\u00e9 et form\u00e9, conform\u00e9ment au mode d&#8217;emploi.<br>Aucune modification de quelque nature que ce soit, \u00e0 l&rsquo;exception de celles d\u00e9crites dans un mode d&#8217;emploi correspondant, n&rsquo;est autoris\u00e9e sur les produits de Kentix GmbH.<br>Lors de l&rsquo;installation d&rsquo;appareils Kentix, certains degr\u00e9s de protection doivent \u00eatre garantis.<br>Respectez \u00e0 cet effet les prescriptions en vigueur pour les installations dans l&rsquo;environnement concern\u00e9.<br>N&rsquo;utilisez les produits que dans la plage de temp\u00e9rature d\u00e9finie.<br>Les instructions doivent \u00eatre transmises \u00e0 l&rsquo;utilisateur par la personne qui proc\u00e8de \u00e0 l&rsquo;installation.<br>Kentix d\u00e9cline toute responsabilit\u00e9 en cas d&rsquo;endommagement des appareils ou des composants suite \u00e0 un montage incorrect. Aucune responsabilit\u00e9 n&rsquo;est assum\u00e9e en cas d&rsquo;unit\u00e9s mal programm\u00e9es.<br>Si des dysfonctionnements, des dommages mat\u00e9riels ou autres surviennent, Kentix n&rsquo;est pas responsable. <br><\/div><\/div><\/div><div class=\"wp-block-hb-accordion__section\" data-ht-blocks-accordion-block-state=\"closed\"><div class=\"wp-block-hb-accordion__title\"><span>Utilisation des produits, transport et stockage<\/span><\/div><div class=\"wp-block-hb-accordion__content\"><div class=\"wp-block-hb-accordion__contentwrap\">Prot\u00e9ger l&rsquo;appareil contre l&rsquo;humidit\u00e9, la salet\u00e9 et les dommages pendant le transport, le stockage et l&rsquo;utilisation<br><\/div><\/div><\/div><div class=\"wp-block-hb-accordion__section\" data-ht-blocks-accordion-block-state=\"closed\"><div class=\"wp-block-hb-accordion__title\"><span>Produits aliment\u00e9s par batterie<\/span><\/div><div class=\"wp-block-hb-accordion__content\"><div class=\"wp-block-hb-accordion__contentwrap\">N&rsquo;utilisez pas les produits dans des zones \u00e0 risque d&rsquo;explosion.<br>N&rsquo;utilisez les produits que dans la plage de temp\u00e9rature d\u00e9finie.<br>L&rsquo;installation ainsi que le remplacement des piles ne doivent \u00eatre effectu\u00e9s que par un personnel qualifi\u00e9 et form\u00e9, conform\u00e9ment aux instructions.<br>Ne chargez pas, ne court-circuitez pas, n&rsquo;ouvrez pas et ne chauffez pas les piles.<br>Lors de la mise en place des piles, veillez \u00e0 respecter la polarit\u00e9.<br>Les appareils doivent toujours \u00eatre aliment\u00e9s par les piles pr\u00e9vues pour le produit.<br>Lors du remplacement des piles, remplacez toujours toutes les piles.<br>\u00c9liminez les piles usag\u00e9es ou us\u00e9es de mani\u00e8re appropri\u00e9e.<br>Conservez les piles hors de port\u00e9e des enfants.  <br><\/div><\/div><\/div><div class=\"wp-block-hb-accordion__section\" data-ht-blocks-accordion-block-state=\"closed\"><div class=\"wp-block-hb-accordion__title\"><span>Maintenance<br><\/span><\/div><div class=\"wp-block-hb-accordion__content\"><div class=\"wp-block-hb-accordion__contentwrap\">Le fonctionnement des appareils Kentix doit \u00eatre contr\u00f4l\u00e9 dans le cadre d&rsquo;une maintenance annuelle.<\/div><\/div><\/div><div class=\"wp-block-hb-accordion__section\" data-ht-blocks-accordion-block-state=\"closed\"><div class=\"wp-block-hb-accordion__title\"><span>\u00c9limination des d\u00e9chets<\/span><\/div><div class=\"wp-block-hb-accordion__content\"><div class=\"wp-block-hb-accordion__contentwrap\">Les appareils \u00e9lectriques et les piles doivent \u00eatre \u00e9limin\u00e9s s\u00e9par\u00e9ment des d\u00e9chets m\u00e9nagers.<br><\/div><\/div><\/div><\/div>\n\n<h2 class=\"wp-block-heading\">\u00c9l\u00e9ments de commande<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-1024x768.jpeg\" alt=\"\" class=\"wp-image-3860\" style=\"width:512px;height:384px\" srcset=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-1024x768.jpeg 1024w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-400x300.jpeg 400w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-150x113.jpeg 150w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-768x576.jpeg 768w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-50x38.jpeg 50w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-1536x1152.jpeg 1536w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-60x45.jpeg 60w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open-100x75.jpeg 100w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-open.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<div class=\"wp-block-ht-blocks-list heroic-styled-list\" id=\"heroic-styled-list-822d2194-7dbc-4a1d-a13c-2b4e7d37b13d\"><ol class=\"fa-ul\"><li>Bouton d&rsquo;apprentissage : Ce bouton sert \u00e0 l&rsquo;apprentissage de l&rsquo;appareil dans le r\u00e9seau sans fil. Pour programmer le capteur dans l&rsquo;interface web du gestionnaire, lancez la proc\u00e9dure d&rsquo;apprentissage puis appuyez sur le bouton d&rsquo;apprentissage pendant 3 secondes jusqu&rsquo;\u00e0 ce que vous entendiez un signal sonore.  <\/li><li>Contact magn\u00e9tique<\/li><\/ol><style>#heroic-styled-list-822d2194-7dbc-4a1d-a13c-2b4e7d37b13d li:before{\n\t\t                   background:#f7931e;\n\t\t                   border-radius: 0;\n\t\t                   }<\/style><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Ouverture du bo\u00eetier et remplacement de la pile<\/h2>\n\n<p class=\"wp-block-paragraph\">La platine du MultiSensor-DOOR se trouve dans la partie sup\u00e9rieure du bo\u00eetier, qui est embo\u00eet\u00e9e sur la partie inf\u00e9rieure. Pour ouvrir le bo\u00eetier, appuyez sur la languette d&rsquo;arr\u00eat situ\u00e9e sur la partie inf\u00e9rieure du bo\u00eetier et faites glisser le couvercle du bo\u00eetier vers le haut. Celui-ci peut alors \u00eatre facilement retir\u00e9. <br\/>Retirez la pile de son support et remplacez-la par un type \u00e9quivalent, voir <a href=\"https:\/\/docs.kentix.com\/fr\/knowledge-base\/multisensor-door-fiche-technique-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">la fiche technique<\/a>.  <\/p>\n\n<p class=\"wp-block-paragraph\">Le niveau de la batterie du MultiSensor-DOOR est surveill\u00e9 en permanence par le gestionnaire. Lorsque le niveau de charge de la batterie est faible, une alerte est envoy\u00e9e par SMS et par e-mail \u00e0 tous les administrateurs. Remplacez alors la batterie d\u00e8s que possible.  <\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-alert\">Notez que le fonctionnement du MultiSensor-DOOR n\u00e9cessite une connexion \u00e0 un Manager.<br\/>Si le MultiSensor n&rsquo;est pas configur\u00e9 dans KentixONE ou si la connexion est interrompue, cela a pour cons\u00e9quence une d\u00e9charge plus rapide de la batterie. <br\/>Veuillez toujours stocker le MultiSensor-DOOR avec la batterie retir\u00e9e.  <\/p>\n\n<h2 class=\"wp-block-heading\">Se connecter au r\u00e9seau sans fil<\/h2>\n\n<div class=\"wp-block-ht-blocks-list heroic-styled-list\" id=\"heroic-styled-list-7ce6751a-20be-467b-a4d8-0cac4c9a5056\"><ol class=\"fa-ul\"><li>MultiSensor-DOOR-BLE doit se trouver \u00e0 port\u00e9e radio d&rsquo;une passerelle Ethernet sans fil enti\u00e8rement configur\u00e9e (MultiSensor-LAN-BLE ou MultiSensor-TI-BLE). Il est recommand\u00e9 d&rsquo;effectuer la proc\u00e9dure d&rsquo;apprentissage plus pr\u00e8s que la port\u00e9e d&rsquo;installation r\u00e9elle, environ 3-5m. <\/li><li>Lancez la proc\u00e9dure d&rsquo;apprentissage dans l&rsquo;interface Web de KentixONE dans la zone \u00ab\u00a0Detail-View\u00a0\u00bb en cliquant sur le bouton \u00ab\u00a0Ajouter un appareil\u00a0\u00bb.<\/li><li>Appuyez maintenant sur la touche d&rsquo;apprentissage du MultiSensor-DOOR-BLE pendant environ 3 secondes alors que la pile est install\u00e9e. Apr\u00e8s environ 5 \u00e0 10 secondes, le MultiSensor-DOOR-BLE devrait \u00eatre reconnu comme un nouveau capteur. <\/li><li>Enfin, effectuez la configuration et placez le MultiSensor-DOOR-BLE \u00e0 l&#8217;emplacement de montage pr\u00e9vu et connectez-le au r\u00e9seau sans fil.<\/li><\/ol><style>#heroic-styled-list-7ce6751a-20be-467b-a4d8-0cac4c9a5056 li:before{\n\t\t                   background:#f7931e;\n\t\t                   border-radius: 0;\n\t\t                   }<\/style><\/div>\n\n<p class=\"wp-block-paragraph\">Instructions de montage<\/p>\n\n<p class=\"wp-block-paragraph\">Pour un fonctionnement optimal, veuillez suivre les instructions suivantes lors de l&rsquo;installation :<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-success\">Monter le MultiSensor-DOOR-BLE uniquement \u00e0 la verticale ou \u00e0 l&rsquo;horizontale sur le c\u00f4t\u00e9 de la poign\u00e9e de la porte ou de la fen\u00eatre.<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon\">Pour \u00e9viter les fausses alertes, placez le MultiSensor-DOOR-BLE sur le cadre de la porte ou de la fen\u00eatre et l&rsquo;aimant sur la partie mobile.<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon\">En cas d&rsquo;utilisation du contact Reed, respectez la distance maximale (1 cm) par rapport \u00e0 l&rsquo;aimant.<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon\">Utiliser uniquement du mat\u00e9riel de montage appropri\u00e9 (bande de mousse)<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon\">Si n\u00e9cessaire, visser le bo\u00eetier du capteur sur le cadre de la porte \/ fen\u00eatre<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-danger\">Kentix d\u00e9cline toute responsabilit\u00e9 en cas de fausses alertes ou d&rsquo;endommagement des appareils en cas d&rsquo;installation non conforme.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-1024x768.png\" alt=\"\" class=\"wp-image-3868\" style=\"width:512px;height:384px\" srcset=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-1024x768.png 1024w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-400x300.png 400w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-150x113.png 150w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-768x576.png 768w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-50x38.png 50w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-1536x1152.png 1536w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-60x45.png 60w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos-100x75.png 100w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_Pos.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact.png\" alt=\"\" class=\"wp-image-3862\" srcset=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact.png 240w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact-120x150.png 120w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact-40x50.png 40w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact-48x60.png 48w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Contact-80x100.png 80w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Utilisation du contact Reed<\/h2>\n\n<p class=\"wp-block-paragraph\">Le contact Reed ajoute un contact d&rsquo;alarme suppl\u00e9mentaire au MultiSensor-DOOR pour une d\u00e9tection claire de l&rsquo;ouverture\/la fermeture de la porte ou de la fen\u00eatre. Le contact r\u00e9agit aux champs magn\u00e9tiques (aimant inclus dans la livraison). Aucun c\u00e2blage n&rsquo;est n\u00e9cessaire pour la mise en service.<br\/>Pour garantir la fonctionnalit\u00e9 du contact, veillez \u00e0 ce que l&rsquo;aimant soit fix\u00e9 \u00e0 une <strong>distance <\/strong>maximale d <strong>&lsquo;un centim\u00e8tre <\/strong>et align\u00e9 sur le c\u00f4t\u00e9 du bo\u00eetier du MultiSensor.  <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-1024x768.png\" alt=\"\" class=\"wp-image-3872\" style=\"width:512px;height:384px\" srcset=\"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-1024x768.png 1024w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-400x300.png 400w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-150x113.png 150w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-768x576.png 768w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-50x38.png 50w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-1536x1152.png 1536w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-60x45.png 60w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation-100x75.png 100w, https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/03\/KMS-DOOR-Magnet_orientation.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Orientation du contact Reed<\/figcaption><\/figure>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Selon le type de construction de la porte ou de la fen\u00eatre, il peut \u00eatre n\u00e9cessaire de placer une entretoise sous l&rsquo;aimant afin de ne pas d\u00e9passer la distance maximale par rapport au capteur.<\/p>\n\n<h2 class=\"wp-block-heading\">Configuration avec KentixONE<\/h2>\n\n<p class=\"wp-block-paragraph\">La configuration de l&rsquo;appareil s&rsquo;effectue via le navigateur web dans KentixONE. Du c\u00f4t\u00e9 du r\u00e9seau, l&rsquo;appareil doit \u00eatre accessible \u00e0 l&rsquo;instance centrale de KentixONE. Selon le type d&rsquo;appareil, une cl\u00e9 de communication ainsi que l&rsquo;adresse IP ou le nom DHCP de l&rsquo;instance centrale de KentixONE doivent \u00e9galement \u00eatre d\u00e9finis sur l&rsquo;appareil (MultiSensor, AccessManager, SmartPDU). En revanche, les cam\u00e9ras IP ou les modules IO peuvent \u00eatre directement int\u00e9gr\u00e9s dans KentixONE.   <\/p>\n\n<p class=\"wp-block-paragraph\">Vous trouverez toutes les informations sur le logiciel dans la section <a href=\"https:\/\/docs.kentix.com\/kentixone\/\" target=\"_blank\" rel=\"noreferrer noopener\">KentixONE<\/a> et la documentation correspondante.<\/p>\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">Avant de commencer la configuration, assurez-vous que le logiciel est \u00e0 jour sur tous les dispositifs Kentix compatibles r\u00e9seau. La version doit \u00eatre la m\u00eame sur tous les appareils. <br><strong>Vous pouvez \u00e0 tout moment effectuer une mise \u00e0 jour du logiciel pour votre instance principale KentixONE et tous les satellites connect\u00e9s via \u00ab\u00a0Syst\u00e8me - Mise \u00e0 jour\u00a0\u00bb.<\/strong><\/p>\n\n<h2 class=\"wp-block-heading\">Logiciel de gestion des batteries<\/h2>\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/docs.kentix.com\/kentixone\/forms\/devices\/DoorLock#wartung\" target=\"_blank\" rel=\"noreferrer noopener\">fonction de gestion de la batterie<\/a> du MultiSensor-DOOR doit \u00eatre activ\u00e9e dans l&rsquo;interface de configuration de KentixONE \u00e0 partir de la version 8.6.0. Apr\u00e8s la premi\u00e8re mise en service du MultiSensor-DOOR ainsi qu&rsquo;apr\u00e8s chaque remplacement de batterie, l&rsquo;activation de cette fonction est n\u00e9cessaire pour garantir un fonctionnement sans d\u00e9faillance. Pour finaliser l&rsquo;activation, il faut ensuite appuyer une fois sur le bouton de programmation.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>FICHE TECHNIQUE PORTE MULTISENSOR-DOOR Le MultiSensor-DOOR-BLE est un MultiSensor fonctionnant sur piles et pouvant \u00eatre mis en r\u00e9seau par radio. Le capteur est particuli\u00e8rement adapt\u00e9 \u00e0 la surveillance des fen\u00eatres et des portes, mais peut \u00e9galement \u00eatre utilis\u00e9 pour la surveillance de l&rsquo;environnement dans les racks informatiques. Pour fonctionner par&#8230;<\/p>\n","protected":false},"author":4,"featured_media":13255,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_crdt_document":"","inline_featured_image":false,"footnotes":""},"ht-kb-category":[273],"ht-kb-tag":[],"class_list":["post-13253","ht_kb","type-ht_kb","status-publish","format-standard","has-post-thumbnail","hentry","ht_kb_category-multisensors-sans-fil"],"custom_fields":{"kentix_order_code":["KMS-DOOR-B-BLE, KMS-DOOR-W-BLE"],"kentix_skill_level":["1"]},"categories":[{"slug":"multisensors-sans-fil","name":"MultiSensors sans fil","shortName":""}],"featured_media_url":"https:\/\/docs.kentix.com\/wp-content\/uploads\/2023\/01\/KMS-DOOR-B-150x113.png","_links":{"self":[{"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb\/13253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/comments?post=13253"}],"version-history":[{"count":14,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb\/13253\/revisions"}],"predecessor-version":[{"id":14389,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb\/13253\/revisions\/14389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/media\/13255"}],"wp:attachment":[{"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/media?parent=13253"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb-category?post=13253"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/docs.kentix.com\/fr\/wp-json\/wp\/v2\/ht-kb-tag?post=13253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}